{"id":8,"date":"2020-07-20T11:32:30","date_gmt":"2020-07-20T15:32:30","guid":{"rendered":"https:\/\/research.butler.edu\/caleb-class-lab\/?page_id=8"},"modified":"2026-01-12T13:21:11","modified_gmt":"2026-01-12T17:21:11","slug":"contact","status":"publish","type":"page","link":"https:\/\/research.butler.edu\/caleb-class-lab\/contact\/","title":{"rendered":"People"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/cdn.butler.edu\/research\/sites\/4\/2026\/01\/12131807\/IMG_2992-1024x768.jpg\" alt=\"\" class=\"wp-image-125\" srcset=\"https:\/\/cdn.butler.edu\/research\/sites\/4\/2026\/01\/12131807\/IMG_2992-1024x768.jpg 1024w, https:\/\/cdn.butler.edu\/research\/sites\/4\/2026\/01\/12131807\/IMG_2992-300x225.jpg 300w, https:\/\/cdn.butler.edu\/research\/sites\/4\/2026\/01\/12131807\/IMG_2992-768x576.jpg 768w, https:\/\/cdn.butler.edu\/research\/sites\/4\/2026\/01\/12131807\/IMG_2992-1536x1152.jpg 1536w, https:\/\/cdn.butler.edu\/research\/sites\/4\/2026\/01\/12131807\/IMG_2992-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Current Group Members<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>David Cooper (Postdoctoral Researcher)<\/li>\n\n\n\n<li>Aayan Ansar (Health Sciences, Class of 2028, co-advised w\/ A. Erkine)<\/li>\n\n\n\n<li>Victoria Gaertig (PharmD, Class of 2027)<\/li>\n\n\n\n<li>Hassan Hashmi (Health Sciences, Class of 2028, co-advised w\/ A. Erkine)<\/li>\n\n\n\n<li>Julia Mansour (PharmD, Class of 2027)<\/li>\n\n\n\n<li>Keely Roe (Biochemistry, Class of 2027, co-advised w\/ A. Erkine)<\/li>\n\n\n\n<li>Ethan Valek (Health Sciences, Class of 2028)<\/li>\n\n\n\n<li>Patrick Vo (PharmD, Class of 2028)<\/li>\n\n\n\n<li>Dina Zidan (Data Science, Class of 2028)<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Former Group Members<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Kathryn Cannaday (PharmD, Class of 2026)<\/li>\n\n\n\n<li>Elizabeth Carys Durbin (Software Engineering, Class of 2025)<\/li>\n\n\n\n<li>Ariel Worthington (PharmD, Class of 2025)<\/li>\n\n\n\n<li>Katrina Retzke (PharmD, Class of 2025)<\/li>\n\n\n\n<li>Jack Karbowski (Biology, Class of 2024)<\/li>\n\n\n\n<li>Caiden Lukan (PharmD, Class of 2024)<\/li>\n\n\n\n<li>Paige Cowden (PharmD, Class of 2023)<\/li>\n\n\n\n<li>Logan Van Ravenswaay (PharmD, Class of 2023)<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Current Group Members Former Group Members<\/p>\n","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>People - Caleb A Class, PhD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/research.butler.edu\/caleb-class-lab\/contact\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"People - Caleb A Class, PhD\" \/>\n<meta property=\"og:description\" content=\"Current Group Members Former Group Members\" \/>\n<meta property=\"og:url\" content=\"https:\/\/research.butler.edu\/caleb-class-lab\/contact\/\" \/>\n<meta property=\"og:site_name\" content=\"Caleb A Class, PhD\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-12T17:21:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/research.butler.edu\/caleb-class-lab\/wp-content\/uploads\/sites\/4\/2026\/01\/IMG_2992-1024x768.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/research.butler.edu\\\/caleb-class-lab\\\/contact\\\/\",\"url\":\"https:\\\/\\\/research.butler.edu\\\/caleb-class-lab\\\/contact\\\/\",\"name\":\"People - Caleb A Class, PhD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/research.butler.edu\\\/caleb-class-lab\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/research.butler.edu\\\/caleb-class-lab\\\/contact\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/research.butler.edu\\\/caleb-class-lab\\\/contact\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/research.butler.edu\\\/caleb-class-lab\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/01\\\/IMG_2992-1024x768.jpg\",\"datePublished\":\"2020-07-20T15:32:30+00:00\",\"dateModified\":\"2026-01-12T17:21:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/research.butler.edu\\\/caleb-class-lab\\\/contact\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/research.butler.edu\\\/caleb-class-lab\\\/contact\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/research.butler.edu\\\/caleb-class-lab\\\/contact\\\/#primaryimage\",\"url\":\"https:\\\/\\\/research.butler.edu\\\/caleb-class-lab\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/01\\\/IMG_2992-1024x768.jpg\",\"contentUrl\":\"https:\\\/\\\/research.butler.edu\\\/caleb-class-lab\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/01\\\/IMG_2992-1024x768.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/research.butler.edu\\\/caleb-class-lab\\\/contact\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/research.butler.edu\\\/caleb-class-lab\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"People\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/research.butler.edu\\\/caleb-class-lab\\\/#website\",\"url\":\"https:\\\/\\\/research.butler.edu\\\/caleb-class-lab\\\/\",\"name\":\"Caleb A Class, PhD\",\"description\":\"Visual Bioinformatics Lab\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/research.butler.edu\\\/caleb-class-lab\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"People - Caleb A Class, PhD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/research.butler.edu\/caleb-class-lab\/contact\/","og_locale":"en_US","og_type":"article","og_title":"People - Caleb A Class, PhD","og_description":"Current Group Members Former Group Members","og_url":"https:\/\/research.butler.edu\/caleb-class-lab\/contact\/","og_site_name":"Caleb A Class, PhD","article_modified_time":"2026-01-12T17:21:11+00:00","og_image":[{"url":"https:\/\/research.butler.edu\/caleb-class-lab\/wp-content\/uploads\/sites\/4\/2026\/01\/IMG_2992-1024x768.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/research.butler.edu\/caleb-class-lab\/contact\/","url":"https:\/\/research.butler.edu\/caleb-class-lab\/contact\/","name":"People - Caleb A Class, PhD","isPartOf":{"@id":"https:\/\/research.butler.edu\/caleb-class-lab\/#website"},"primaryImageOfPage":{"@id":"https:\/\/research.butler.edu\/caleb-class-lab\/contact\/#primaryimage"},"image":{"@id":"https:\/\/research.butler.edu\/caleb-class-lab\/contact\/#primaryimage"},"thumbnailUrl":"https:\/\/research.butler.edu\/caleb-class-lab\/wp-content\/uploads\/sites\/4\/2026\/01\/IMG_2992-1024x768.jpg","datePublished":"2020-07-20T15:32:30+00:00","dateModified":"2026-01-12T17:21:11+00:00","breadcrumb":{"@id":"https:\/\/research.butler.edu\/caleb-class-lab\/contact\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/research.butler.edu\/caleb-class-lab\/contact\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/research.butler.edu\/caleb-class-lab\/contact\/#primaryimage","url":"https:\/\/research.butler.edu\/caleb-class-lab\/wp-content\/uploads\/sites\/4\/2026\/01\/IMG_2992-1024x768.jpg","contentUrl":"https:\/\/research.butler.edu\/caleb-class-lab\/wp-content\/uploads\/sites\/4\/2026\/01\/IMG_2992-1024x768.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/research.butler.edu\/caleb-class-lab\/contact\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/research.butler.edu\/caleb-class-lab\/"},{"@type":"ListItem","position":2,"name":"People"}]},{"@type":"WebSite","@id":"https:\/\/research.butler.edu\/caleb-class-lab\/#website","url":"https:\/\/research.butler.edu\/caleb-class-lab\/","name":"Caleb A Class, PhD","description":"Visual Bioinformatics Lab","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/research.butler.edu\/caleb-class-lab\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/research.butler.edu\/caleb-class-lab\/wp-json\/wp\/v2\/pages\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/research.butler.edu\/caleb-class-lab\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/research.butler.edu\/caleb-class-lab\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/research.butler.edu\/caleb-class-lab\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/research.butler.edu\/caleb-class-lab\/wp-json\/wp\/v2\/comments?post=8"}],"version-history":[{"count":8,"href":"https:\/\/research.butler.edu\/caleb-class-lab\/wp-json\/wp\/v2\/pages\/8\/revisions"}],"predecessor-version":[{"id":128,"href":"https:\/\/research.butler.edu\/caleb-class-lab\/wp-json\/wp\/v2\/pages\/8\/revisions\/128"}],"wp:attachment":[{"href":"https:\/\/research.butler.edu\/caleb-class-lab\/wp-json\/wp\/v2\/media?parent=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}